{"id":61,"count":21,"description":"","link":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/","name":"Ein Tag in...","slug":"ein-tag-in","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ein Tag in... | OLIMAR Sonnenseiten<\/title>\n<meta name=\"description\" content=\"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Tag in... | OLIMAR Sonnenseiten\" \/>\n<meta property=\"og:description\" content=\"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.olimar.de\/wp-content\/uploads\/2015\/02\/Logo_Favicon_512x512-54f0321ev1_site_icon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/\",\"url\":\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/\",\"name\":\"Ein Tag in... | OLIMAR Sonnenseiten\",\"isPartOf\":{\"@id\":\"https:\/\/blog.olimar.de\/#website\"},\"description\":\"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...\",\"breadcrumb\":{\"@id\":\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.olimar.de\/category\/ein-tag-in\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/blog.olimar.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Tag in...\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.olimar.de\/#website\",\"url\":\"https:\/\/blog.olimar.de\/\",\"name\":\"OLIMAR.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/blog.olimar.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.olimar.de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/blog.olimar.de\/#organization\",\"name\":\"OLIMAR Reisen\",\"url\":\"https:\/\/blog.olimar.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/blog.olimar.de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/blog.olimar.de\/wp-content\/uploads\/2021\/01\/OLIMAR_Logo_COLOR.png\",\"contentUrl\":\"https:\/\/blog.olimar.de\/wp-content\/uploads\/2021\/01\/OLIMAR_Logo_COLOR.png\",\"width\":2000,\"height\":986,\"caption\":\"OLIMAR Reisen\"},\"image\":{\"@id\":\"https:\/\/blog.olimar.de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/OlimarReisen\",\"https:\/\/x.com\/olimarrreisen\",\"https:\/\/www.instagram.com\/olimarreisen\",\"https:\/\/www.youtube.com\/user\/olimarreisen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Tag in... | OLIMAR Sonnenseiten","description":"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Tag in... | OLIMAR Sonnenseiten","og_description":"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...","og_url":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/","og_image":[{"width":512,"height":512,"url":"https:\/\/blog.olimar.de\/wp-content\/uploads\/2015\/02\/Logo_Favicon_512x512-54f0321ev1_site_icon.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/","url":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/","name":"Ein Tag in... | OLIMAR Sonnenseiten","isPartOf":{"@id":"https:\/\/blog.olimar.de\/#website"},"description":"Auf den OLIMAR Sonnenseiten finden Sie Reiseberichte mit wertvollen Erfahrungen und Insider-Tipps. Hier finden Sie alle Artikel der Kategorie Ein Tag in...","breadcrumb":{"@id":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.olimar.de\/category\/ein-tag-in\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.olimar.de\/"},{"@type":"ListItem","position":2,"name":"Ein Tag in..."}]},{"@type":"WebSite","@id":"https:\/\/blog.olimar.de\/#website","url":"https:\/\/blog.olimar.de\/","name":"OLIMAR.com","description":"","publisher":{"@id":"https:\/\/blog.olimar.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.olimar.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/blog.olimar.de\/#organization","name":"OLIMAR Reisen","url":"https:\/\/blog.olimar.de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/blog.olimar.de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.olimar.de\/wp-content\/uploads\/2021\/01\/OLIMAR_Logo_COLOR.png","contentUrl":"https:\/\/blog.olimar.de\/wp-content\/uploads\/2021\/01\/OLIMAR_Logo_COLOR.png","width":2000,"height":986,"caption":"OLIMAR Reisen"},"image":{"@id":"https:\/\/blog.olimar.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OlimarReisen","https:\/\/x.com\/olimarrreisen","https:\/\/www.instagram.com\/olimarreisen","https:\/\/www.youtube.com\/user\/olimarreisen"]}]}},"_links":{"self":[{"href":"https:\/\/blog.olimar.de\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.olimar.de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blog.olimar.de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blog.olimar.de\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}